{"id":75627,"date":"2025-09-27T08:03:08","date_gmt":"2025-09-27T08:03:08","guid":{"rendered":"https:\/\/slowmoov.com\/hebergement\/sans-village\/der-blitz\/"},"modified":"2026-01-30T22:35:50","modified_gmt":"2026-01-30T22:35:50","slug":"le-foudre","status":"publish","type":"hebergement","link":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/","title":{"rendered":"Blitzschlag"},"content":{"rendered":"&#13;\n<p>Haben Sie Lust auf einen thematischen Aufenthalt rund um die ber\u00fchmten Champagnerweine? Versuchen Sie die ungew\u00f6hnliche Erfahrung, <strong>in einem Fass zu schlafen<\/strong>! Das Fass ist eine <strong>unserer originellsten atypischen Unterk\u00fcnfte <\/strong>. Perfekt f\u00fcr einen Aufenthalt zu zweit! <\/p>&#13;\n&#13;\n<p>\u00a0<\/p>&#13;\n&#13;\n<p>\u00a0<\/p>&#13;\n","protected":false},"featured_media":82077,"template":"","tags":[181],"village":[193],"personnes":[196],"charmes":[224],"experience":[241,229],"voyageur_maximum":[271],"class_list":["post-75627","hebergement","type-hebergement","status-publish","has-post-thumbnail","hentry","tag-dorf-in-der-champagne","village-dorf-champagne","personnes-2-personen","charmes-faesser","experience-in-der-naehe-von-nigoland","experience-weintourismus","voyageur_maximum-2-personnes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer<\/title>\n<meta name=\"description\" content=\"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/\" \/>\n<meta property=\"og:site_name\" content=\"SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/slowmoov\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T22:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/Chassenard_J2-5-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@slowmoov\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/\",\"url\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/\",\"name\":\"Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/slowmoov.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Foudre-Village-de-la-champagne-e1777472019612.webp\",\"datePublished\":\"2025-09-27T08:03:08+00:00\",\"dateModified\":\"2026-01-30T22:35:50+00:00\",\"description\":\"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/slowmoov.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Foudre-Village-de-la-champagne-e1777472019612.webp\",\"contentUrl\":\"https:\\\/\\\/slowmoov.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Foudre-Village-de-la-champagne-e1777472019612.webp\",\"width\":1153,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/dorf-champagne\\\/le-foudre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9bergements\",\"item\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/hebergement\\\/%village%\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blitzschlag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/\",\"name\":\"SlowMoov - Villages insolites\",\"description\":\"Venez passer vos prochaines vacances originales chez Slowmoov !\",\"publisher\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#organization\",\"name\":\"SlowMoov\",\"url\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/slowmoov.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-slowmoov-1.png\",\"contentUrl\":\"https:\\\/\\\/slowmoov.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-slowmoov-1.png\",\"width\":2234,\"height\":716,\"caption\":\"SlowMoov\"},\"image\":{\"@id\":\"https:\\\/\\\/slowmoov.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/slowmoov\\\/\",\"https:\\\/\\\/x.com\\\/slowmoov\",\"https:\\\/\\\/www.instagram.com\\\/slowmoov_villages_insolites\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqwuY0zlhJy1YsVWbnm-V7A\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer","description":"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/","og_locale":"de_DE","og_type":"article","og_title":"Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer","og_description":"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.","og_url":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/","og_site_name":"SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer","article_publisher":"https:\/\/www.facebook.com\/slowmoov\/","article_modified_time":"2026-01-30T22:35:50+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/Chassenard_J2-5-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@slowmoov","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/","url":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/","name":"Blitzschlag - SlowMoov \u2013 Au\u00dfergew\u00f6hnliche D\u00f6rfer","isPartOf":{"@id":"https:\/\/slowmoov.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/#primaryimage"},"image":{"@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/#primaryimage"},"thumbnailUrl":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/Foudre-Village-de-la-champagne-e1777472019612.webp","datePublished":"2025-09-27T08:03:08+00:00","dateModified":"2026-01-30T22:35:50+00:00","description":"Entdecken Sie eine der originellsten unserer atypischen Unterk\u00fcnfte! Ob Sie nun die Weinberge von Burgund entdecken oder die Stra\u00dfe der Champagne befahren.","breadcrumb":{"@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/#primaryimage","url":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/Foudre-Village-de-la-champagne-e1777472019612.webp","contentUrl":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/Foudre-Village-de-la-champagne-e1777472019612.webp","width":1153,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/slowmoov.com\/de\/hebergement\/dorf-champagne\/le-foudre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/slowmoov.com\/de\/"},{"@type":"ListItem","position":2,"name":"H\u00e9bergements","item":"https:\/\/slowmoov.com\/de\/hebergement\/%village%\/"},{"@type":"ListItem","position":3,"name":"Blitzschlag"}]},{"@type":"WebSite","@id":"https:\/\/slowmoov.com\/de\/#website","url":"https:\/\/slowmoov.com\/de\/","name":"SlowMoov - Villages insolites","description":"Venez passer vos prochaines vacances originales chez Slowmoov !","publisher":{"@id":"https:\/\/slowmoov.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/slowmoov.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/slowmoov.com\/de\/#organization","name":"SlowMoov","url":"https:\/\/slowmoov.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/slowmoov.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/logo-slowmoov-1.png","contentUrl":"https:\/\/slowmoov.com\/wp-content\/uploads\/2025\/09\/logo-slowmoov-1.png","width":2234,"height":716,"caption":"SlowMoov"},"image":{"@id":"https:\/\/slowmoov.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/slowmoov\/","https:\/\/x.com\/slowmoov","https:\/\/www.instagram.com\/slowmoov_villages_insolites\/","https:\/\/www.youtube.com\/channel\/UCqwuY0zlhJy1YsVWbnm-V7A"]}]}},"_links":{"self":[{"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/hebergement\/75627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/types\/hebergement"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/media\/82077"}],"wp:attachment":[{"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/media?parent=75627"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/tags?post=75627"},{"taxonomy":"village","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/village?post=75627"},{"taxonomy":"personnes","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/personnes?post=75627"},{"taxonomy":"charmes","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/charmes?post=75627"},{"taxonomy":"experience","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/experience?post=75627"},{"taxonomy":"voyageur_maximum","embeddable":true,"href":"https:\/\/slowmoov.com\/de\/wp-json\/wp\/v2\/voyageur_maximum?post=75627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}